{"id":1902,"count":1,"description":"","link":"https:\/\/www.sterlingholidays.com\/blog\/tag\/best-honeymoon-resorts-in-kodaikanal\/","name":"best honeymoon resorts in kodaikanal","slug":"best-honeymoon-resorts-in-kodaikanal","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.sterlingholidays.com\/blog\/wp-json\/wp\/v2\/tags\/1902"}],"collection":[{"href":"https:\/\/www.sterlingholidays.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sterlingholidays.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sterlingholidays.com\/blog\/wp-json\/wp\/v2\/posts?tags=1902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}