{"id":1954,"count":1,"description":"","link":"https:\/\/www.sterlingholidays.com\/blog\/tag\/kedarnath-badrinath-temple-images\/","name":"kedarnath badrinath temple images","slug":"kedarnath-badrinath-temple-images","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.sterlingholidays.com\/blog\/wp-json\/wp\/v2\/tags\/1954"}],"collection":[{"href":"https:\/\/www.sterlingholidays.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sterlingholidays.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sterlingholidays.com\/blog\/wp-json\/wp\/v2\/posts?tags=1954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}